{"id":1388,"date":"2025-08-19T19:34:06","date_gmt":"2025-08-19T17:34:06","guid":{"rendered":"https:\/\/mark-schoder.de\/?p=1388"},"modified":"2025-08-19T19:37:13","modified_gmt":"2025-08-19T17:37:13","slug":"ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen","status":"publish","type":"post","link":"https:\/\/mark-schoder.de\/en\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/","title":{"rendered":"Ein Chaos mit System: Der Meggerwald soll sch\u00fctzen, liefern, heilen"},"content":{"rendered":"<p><em>Aus matschigem Boden ragen abges\u00e4gte St\u00fcmpfe, in den Wipfeln zwitschert es: Willkommen im Meggerwald \u2013 einem Chaos mit System, einem Dickicht der Bed\u00fcrfnisse. \u00dcber 200 Eigner\u00efnnen verfolgen hier jeweils eigene Interessen. Aber genau darin k\u00f6nnten sich Chancen verbergen. Eine <a href=\"https:\/\/www.riffreporter.de\/de\/umwelt\/meggerwald-klimawandel-waldpflege-biodiversitaet-forstwirtschaft\">Reportage <\/a>aus dem Osten der Schweiz.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/riff.media\/cdn-cgi\/image\/width=3840,quality=75\/images\/meggerwald-waldpflege-schweiz-foerster-zukunft-11.jpg?w=2300&amp;h=1293&amp;fit=crop-50-35&amp;s=a692e34013f1b996739e640d3dda65b5\" alt=\"F\u00f6rster Lukas Gerig geht durch den Meggerwald in Luzern.\"\/><\/figure>\n\n\n\n<p>Der Meggerwald ist kein M\u00e4rchenwald. Er ist Streitort, Experimentierfeld, Lebensraum und Naturexil f\u00fcr St\u00e4dter\u00efnnen. Hier zeigt sich exemplarisch, wie schwierig Waldpflege im 21. Jahrhundert geworden ist \u2013 zwischen Artensterben, Klimakrise, Rohstoffhunger und Menschen, die ihren Wald lieben, aber oft nicht mehr verstehen.<\/p>\n\n\n\n<p>In diesem Wald wirkt Lukas Gerig. Sein Team hegt einen Wald, der das \u00bbSchmuckk\u00e4stchen der Schweiz\u00ab s\u00e4umt, die reichste Gemeinde hierzulande: Meggen im Kanton Luzern. Gerig ist hier Betriebsf\u00f6rster und setzt damit diverse Interessen von Waldeigent\u00fcmern um. Einige sind emotional mit dem Erbe ihres Waldst\u00fccks stark verbunden, andere hingegen wissen nicht einmal, wo es sich befindet.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/riff.media\/cdn-cgi\/image\/width=3840,quality=75\/images\/meggerwald-waldpflege-schweiz-foerster-zukunft-16.jpg?w=3600&amp;s=5f2c1ded1b0c4d78883e665521652e1d\" alt=\"Man sieht einen F\u00f6rster im Portr\u00e4t: Lukas Gerig aus Meggen, Luzern.\"\/><figcaption class=\"wp-element-caption\">Noch bescheinigt Lukas Gerig dem Meggerwald einen guten Zustand. In der Klimakrise muss er Weiher schaffen, B\u00e4ume s\u00e4en und verschiedenste Interessen moderieren, damit das so bleibt.<\/figcaption><\/figure>\n\n\n\n<p>Manche Waldfl\u00e4chen geh\u00f6ren Erbgemeinschaften, andere einer Landwirtin, einer Kirchen- oder politischen Gemeinde. Die Eigent\u00fcmerinnen kann man kaum kategorisieren. Sie sind Abbilder der Gesellschaft. Die Vorstellungen, wie ihr Waldst\u00fcck auszusehen hat, gehen auseinander. So setzen manche darauf, Rohstoffe zu gewinnen, w\u00e4hrend andere ihre Parzelle in eine biodiverse Brache verwandeln \u2013 oder gar nichts tun. Das ist Waldpolitik im Kleinformat: viele Interessen, wenig Konsens.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Er will morsche Asthaufen statt Bl\u00fcmchenwiesen<\/h2>\n\n\n\n<p>\u00bbDas ist der sch\u00f6nste Wald der Schweiz!\u00ab, ruft ein Jogger dem F\u00f6rster zu. Mit seiner N\u00e4he zur Stadt Luzern lockt der Meggerwald als Erholungsort. Auch zum Grillen geht man mit der Familie in den Erlebnisraum Wald. \u00bbAber das Verst\u00e4ndnis, was dort eigentlich passiert, geht verloren\u00ab, sagt Gerig. Der F\u00f6rster beobachtet, wie sich die Gesellschaft zunehmend von der Natur distanziert, entfremdet. Wie ein Wald zu sein hat, schwanke bei immer mehr Menschen zwischen einer Parkanlage und unber\u00fchrter Wildnis. Dabei ist gerade das, was zwischen diesen Extremen passiert, das Spannende.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/riff.media\/cdn-cgi\/image\/width=3840,quality=75\/images\/meggerwald-waldpflege-schweiz-foerster-zukunft-8.jpg?w=2300&amp;s=7c95537c0e4cc5ac8952c29ad72c7a59\" alt=\"Man sieht einen Baumstumpf im Meggerwald, Luzern.\"\/><figcaption class=\"wp-element-caption\">Gef\u00e4llte oder umgest\u00fcrzte B\u00e4ume bieten einen neuen Lebensraum f\u00fcr Flora und Fauna im Meggerwald.<\/figcaption><\/figure>\n\n\n\n<p>Lukas Gerig betritt einen Trampelpfad, der sich um Baumst\u00fcmpfe und faulende Asthaufen windet. Kaum ein Kind w\u00fcrde hier Verstecken spielen \u2013 zu dunkel, zu unordentlich. Vor einigen Jahrzehnten \u00bbwar der Wald immer super aufger\u00e4umt\u00ab, sagt der F\u00f6rster, weil man das Totholz verfeuerte. Heute sei das anders, und F\u00f6rster m\u00fcssen erkl\u00e4ren, warum. Es braucht \u00bbChaos\u00ab f\u00fcr neuen Lebensraum, in dem es zirpt und surrt. Weil der Mensch die Natur \u00fcberall zur\u00fcckdr\u00e4ngt, soll wenigstens der Wald artenreiche R\u00e4ume in einem intakten \u00d6kosystem bieten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Zu einem gesunden Wald geh\u00f6ren Holzschl\u00e4ge<\/h2>\n\n\n\n<p>Dennoch k\u00f6nne es sinnvoll sein, dem Wald Holz zu entnehmen. Wenn Gerigs Team B\u00e4ume f\u00e4llt, mache es das nicht aus Profitgier. Hievt er \u00e4ltere B\u00e4ume aus dem Wald, schafft das offene Fl\u00e4chen \u2013 und damit Licht und Luft f\u00fcr junge B\u00e4ume. Flackert das Sonnenlicht durch die Bl\u00e4tter, bietet das die Chance zu keimen, verdunkelnde Brombeerstr\u00e4ucher zu \u00fcberwinden und gen Sonne zu ranken.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/riff.media\/cdn-cgi\/image\/width=3840,quality=75\/images\/meggerwald-waldpflege-schweiz-foerster-zukunft-16-1.jpg?w=3600&amp;s=4cdf58deff2e9abf9c792f5e3577cae1\" alt=\"Kahle Waldfl\u00e4che als Folge mehrerer St\u00fcrme im Meggerwald.\"\/><figcaption class=\"wp-element-caption\">Drohnenaufnahme von einer Waldparzelle im Meggerwald: Hier w\u00fcteten St\u00fcrme und knickten Dutzende B\u00e4ume ab.<\/figcaption><\/figure>\n\n\n\n<p>Im Meggerwald beschleunigen F\u00f6rster mit Holzschl\u00e4gen diese nat\u00fcrliche Sukzession. Denn \u00bbwas der Mensch nicht aus dem Wald holt, erledigt die Natur von selbst\u00ab, etwa nach einem Sturm, sagt Gerig. Er sieht im Wald \u00bbein riesengro\u00dfes Potenzial, Synergien f\u00fcr eine Kreislaufwirtschaft zu nutzen.\u00ab Den Wald als Baumarkt zu begreifen, funktioniere allerdings nicht, sagt Gerig. Er unterst\u00fctzt nat\u00fcrliche Abl\u00e4ufe, st\u00f6\u00dft an oder bremst. Der F\u00f6rster sagt: \u00bbGenerell entwerfe ich keinen Bauplan vom Wald, sondern greife ein und lenke.\u00ab Jeder Hektar braucht seine eigene Therapie, die er begleiten, aber nicht dominieren kann.<\/p>\n\n\n\n<p>Einige Meter weiter merkt selbst das unge\u00fcbte Auge, wie fragmentiert der Wald ist: Baumst\u00fcmpfe neben jungen B\u00e4umen zeigen, dass diese Parzelle jemand anderes verantwortet als die, in der es im Waldweiher pl\u00e4tschert und das Unterholz wuchert. Mancherorts stecken \u00c4sthetik und Erholung zur\u00fcck, weil Eigent\u00fcmerinnen nachwachsenden Baustoff gewinnen wollen. Betriebsf\u00f6rster Gerig ber\u00e4t sie und stellt sicher, das Holz zu schlagen, abzutransportieren und zu verkaufen. Dabei muss er alles mit der jeweiligen Waldeigent\u00fcmerin absprechen, denn er darf keine Ma\u00dfnahme eigenh\u00e4ndig durchf\u00fchren oder anordnen.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/riff.media\/cdn-cgi\/image\/width=3840,quality=75\/images\/meggerwald-waldpflege-schweiz-foerster-zukunft-12.jpg?w=2300&amp;s=d967887787e66e83055fc4425db6db61\" alt=\"Jungp\u00e4ume wachsen, umz\u00e4unt, auf einer Waldparzelle.\"\/><figcaption class=\"wp-element-caption\">Sieht nicht h\u00fcbsch aus, kann sich aber \u00f6kologisch auszahlen: Nach einem Sturm p\u00e4ppelt der F\u00f6rster auf dieser Parzelle Jungb\u00e4ume auf.<\/figcaption><\/figure>\n\n\n\n<p>Nur fehlt es an H\u00e4nden, die diesen Wandel antreiben. Insgesamt ist die Wirtschaftlichkeit des Waldes bedroht. Fachkr\u00e4fte fehlen, und die wenigen, die es noch gibt, beklagen miese L\u00f6hne. Arbeit im Wald lohnt nicht mehr.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00bbWir sollten uns fragen: Was ist es unserer Gesellschaft wert, Fl\u00e4chen offenzuhalten?\u00ab<\/p>\n<\/blockquote>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/riff.media\/cdn-cgi\/image\/width=3840,quality=75\/images\/meggerwald-waldpflege-schweiz-foerster-zukunft-9.jpg?w=2300&amp;s=446ee2f3f265b216c395e788f24395e1\" alt=\"Licht bricht durch das Bl\u00e4tterdach im Meggerwald.\"\/><figcaption class=\"wp-element-caption\">Dort, wo B\u00e4ume den Boden nicht mehr verschatten, dringt Licht durch und erschwert es Brombeerstr\u00e4uchern, zu wuchern.<\/figcaption><\/figure>\n\n\n\n<p>Das Label \u00bbSchweizer Holz\u00ab hilft \u2013 f\u00fcr den Geldbeutel, aber auch, damit Waldarbeitende nicht in einen Topf geworfen werden mit der Rodungsindustrie im Regenwald: \u00bbWir haben in der Schweiz ein extrem restriktives Waldgesetz und d\u00fcrfen gar kein Raubbau an der Natur betreiben\u00ab, sagt Gerig. Er k\u00e4mpft gegen die weit verbreitete Haltung, dass Holznutzung die Umwelt zerst\u00f6re.<\/p>\n\n\n\n<p>Dennoch verh\u00e4lt es sich heute oft so: Wo die Motors\u00e4ge l\u00e4rmt, beginnt eine Debatte \u2013 und nicht selten ein Missverst\u00e4ndnis. Er werde oft von Passanten \u00bbals Umweltzerst\u00f6rer beschimpft\u00ab. Eigentlich m\u00fcsse in der Schweiz noch mehr Holz geschlagen werden, da der landesweite Waldbestand \u00fcberaltert. Allerdings herrscht im Schweizer Wald keine Bewirtschaftungspflicht. Mancherorts \u00bbsetzt deswegen niemand den Wald in Wert\u00ab, sagt der F\u00f6rster. Anderswo gibt es den Rohstoff g\u00fcnstiger. Dort bewegt sich die Holzwirtschaft auf ein \u00bbrace to the bottom\u00ab zu, bei dem mehr B\u00e4ume abgeholzt werden, als neue nachwachsen k\u00f6nnen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Die Klimakrise im Wurzelwerk<\/h2>\n\n\n\n<p>Dabei sind gesunde und robuste W\u00e4lder wichtiger denn je: In Zukunft werden sich die stabilen Gro\u00dfwetterlagen h\u00e4ufen. Das h\u00f6rt sich harmlos an, bedeutet aber: Es regnet wochen- und monatelang gar nicht oder extrem intensiv. Auch an diesem Tag f\u00e4llt kein Regentropfen auf den Waldboden.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/riff.media\/cdn-cgi\/image\/width=3840,quality=75\/images\/meggerwald-waldpflege-schweiz-foerster-zukunft-1.jpg?w=3600&amp;s=eb8f7cf2de2e327f839d4f898d3a32ef\" alt=\"Ein Spinnennetz klebt zwischen Zweigen eines Baums im Meggerwald, Luzern.\"\/><figcaption class=\"wp-element-caption\">Man muss genau hinschauen, um die lebendige Vielfalt im sommerlichen Meggerwald zu erkennen.<\/figcaption><\/figure>\n\n\n\n<p>Schon heute versucht Gerig den Meggerwald, der zu drei Vierteln aus Nadelholz besteht, \u00bbklimafit\u00ab zu machen. Doch wer den Wald auf Zukunft trimmen will, muss erst mit der Vergangenheit aufr\u00e4umen. Im langfristigen \u00d6kosystem Wald sind die Spuren seiner Vorg\u00e4nger sichtbar. Einst pflanzten sie Fichten als profitables Geh\u00f6lz. Sie werden vom Wild vergr\u00e4mt und wachsen rasch. Heute sind sie verletzbar geworden. Als Flachwurzler sind sie, wie F\u00f6rsterinnen sagen, \u00bbwindwurfgef\u00e4hrdet\u00ab. Und sobald die obersten Bodenschichten austrocknen, fehlt ihnen <a href=\"https:\/\/mark-schoder.de\/en\/das-tote-meer-stirbt-und-nu\/\">Wasser<\/a>. Der Borkenk\u00e4fer st\u00fcrzt sich auf die vom Durst geschw\u00e4chten B\u00e4ume.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00bbMonokulturen sind ein viel zu hohes Risiko. Deswegen sage ich: Immer m\u00f6glichst divers fahren und das Risiko streuen.\u00ab<\/p>\n<\/blockquote>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/riff.media\/cdn-cgi\/image\/width=3840,quality=75\/images\/meggerwald-waldpflege-schweiz-foerster-zukunft-3.jpg?w=2300&amp;s=ae75cccfae5eeb1eb2db449478ad3432\" alt=\"Man sieht die d\u00fcnnen, hohen Fichten im Meggerwald, Luzern.\"\/><figcaption class=\"wp-element-caption\">Nach wie vor dominieren Fichten die Szenerie im Meggerwald.<\/figcaption><\/figure>\n\n\n\n<p>Steigen die Temperaturen, erh\u00f6ht sich f\u00fcr den F\u00f6rster auch der Druck zu handeln. \u00bbImmerhin wissen wir heute viel mehr als fr\u00fchere Generationen\u00ab, sagt er. \u00bbDie Natur in ihrer Gesamtheit zu \u00fcberschauen und zu verstehen\u00ab k\u00f6nne er nicht. Umso wichtiger sind Experimente: Neues ausprobieren, Fehler machen, zusehen, lernen, wie Gerig sagt.<\/p>\n\n\n\n<p>Grunds\u00e4tzlich wollen Schweizer F\u00f6rster zur\u00fcck zu \u00bbnaturnahen Mischw\u00e4ldern\u00ab. Nach und nach ersetzt Gerig Fichten und andere (Halb-)Schattenbaumarten durch Eichen und Artgenossen, die W\u00e4rme und Licht lieben.<\/p>\n\n\n\n<p>Vor allem setzt sein Team darauf, die einheimischen Baumarten nat\u00fcrlich zu verj\u00fcngen. Denn sind diese noch frisch und vital, passen sie sich erstens besser an den Klimawandel an. Und zweitens k\u00f6nnen sie in ihrer Wachstumsphase deutlich mehr Treibhausgase speichern als alte B\u00e4ume. Noch binden Schweizer W\u00e4lder mehr CO<sub>2<\/sub>&nbsp;als sie freisetzen. Anders als deutsche W\u00e4lder, die sich landesweit von der CO<sub>2<\/sub>-Senke zur CO<sub>2<\/sub>-Quelle gewandelt haben. Setze sein Team aber die S\u00e4ge an, gebe es schnell einen gesellschaftlichen Konflikt, weil sie \u00bbalte wundersch\u00f6ne Buchen\u00ab f\u00e4llten, sagt Gerig.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/riff.media\/cdn-cgi\/image\/width=3840,quality=75\/images\/meggerwald-waldpflege-schweiz-foerster-zukunft-17.jpg?w=3600&amp;s=00508ab3d65d652c40e792a5491ceb13\" alt=\"Blick auf das Bl\u00e4tterdach des Meggerwalds in der Zentralschweiz, von Sonnenlicht beschienen.\"\/><figcaption class=\"wp-element-caption\">Ein F\u00f6rster kann prim\u00e4r mit dem Licht im Wald spielen, da weder Wind noch Niederschlag in seiner Macht stehen.<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Wasser gibt\u2019s genug<\/h2>\n\n\n\n<p>Die gute Nachricht: Der Meggerwald verdurstet nicht so schnell wie W\u00e4lder auf trockenem Kalkboden, etwa im Jura, in S\u00fcddeutschland oder \u00d6sterreich. Auf rund f\u00fcnf Quadratkilometern w\u00e4chst er auf den Mor\u00e4nen eines einstigen Gletschers. Das bedeutet, dass \u00bbbesondere Waldgesellschaften\u00ab auf den sauren, trockenen Kuppen und nassen Senken der gewellten Landschaft wachsen, wie etwa Moorbirken oder Sumpf-Blutaugen.<\/p>\n\n\n\n<p>Um noch mehr verschiedene Tiere und Pflanzen in den Wald zu bringen, hebt Gerig einige dieser Senken bis auf die Lehmschichten aus und streicht die Grube mit Lehm aus \u2013 fertig ist ein Waldweiher. Innerhalb von ein bis zwei Jahren ziehen seltene Arten wie die Gelbbauchunke und Ringelnatter ein. Wo Wasser ist, brummt das Leben. Und das sei letztlich f\u00fcr alle Eignerinnen gut: Ein intaktes \u00d6kosystem ist der Grundpfeiler daf\u00fcr, unterschiedliche Bed\u00fcrfnisse im Wald zu stillen.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/riff.media\/cdn-cgi\/image\/width=3840,quality=75\/images\/meggerwald-waldpflege-schweiz-foerster-zukunft-7.jpg?w=2300&amp;s=b27c04eb2abf6724a6f128e1db752205\" alt=\"Man sieht einen umwucherten Waldweiher im Luzerner Meggerwald.\"\/><figcaption class=\"wp-element-caption\">Waldweiher wie diesen hob der F\u00f6rster und sein Team aus, um einer neuen Artenvielfalt Raum zu geben.<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">In der Klimakrise gleicht die Arbeit der von Sisyphos<\/h2>\n\n\n\n<p>Doch ein solches intaktes \u00d6kosystem zu schaffen oder zumindest zu f\u00f6rdern, ist nicht immer leicht. Gerig stoppt vor einem anderthalb Hektar gro\u00dfen Gebiet, das 2018 erst Sturmtief Burglind, ein Jahr sp\u00e4ter ein starkes Gewitter, danach der Borkenk\u00e4fer und 2020 ein weiteres Unwetter verheerte. Auf der Lichtung ragen zersplitterte St\u00e4mme empor, neben ihnen wachsen umz\u00e4unte Jungb\u00e4ume. Gerig sagt: \u00bbDie ersten zwei Jahre nach 2020 hat mir das Gebiet hier keine Freude bereitet.\u00ab All die Tiefschl\u00e4ge in \u00bbseinem\u00ab Wald setzten dem F\u00f6rster zu.<\/p>\n\n\n\n<p>Doch dann begann er, diverse Baumarten anzupflanzen und die Flora zu verj\u00fcngen. Mit Blick auf die umz\u00e4unten Jungb\u00e4ume sagt er: \u00bbWenn ich das heute sehe, ist das eine Riesenfreude.\u00ab Heute wachsen dort Pionierinnen wie die Birke oder die Vogelbeere und klimataugliche Baumarten wie Eiche, Kirsche, Kastanie, F\u00f6hre. Sie florieren neben altbekannten Tannen, Buchen und ja \u2013 auch Fichten.<\/p>\n\n\n\n<p>Gerig f\u00e4hrt einen pragmatischen Ansatz. F\u00fcr ihn scheint es sinnlos, den Waldbestand nur eindimensional, also auf eine Waldfunktion ausgerichtet, zu bewirtschaften. Deswegen lehnt er es ab, Waldbest\u00e4nde nur durch Wasserfl\u00e4chen f\u00fcr einige Tierarten zu ersetzen:<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/riff.media\/cdn-cgi\/image\/width=3840,quality=75\/images\/meggerwald-waldpflege-schweiz-foerster-zukunft-19.jpg?w=3600&amp;s=747217e76e783d5eceb588231f193f09\" alt=\"Blick in einen Wald in der Zentralschweiz, von Sonnenlicht durchstr\u00f6mt.\"\/><figcaption class=\"wp-element-caption\">Lukas Gerig umsorgt den Meggerwald im Schweizer Kanton Luzern und l\u00e4uft mehrmals die Woche auf seinen Pfaden.<\/figcaption><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>\u00bbManche konzentrieren sich auf Tagfalter und Schmetterlinge, andere auf Gr\u00e4ser oder Kastanien. Diesen Tunnelblick muss man \u00f6ffnen.\u00ab<\/p>\n<\/blockquote>\n\n\n\n<p>Die Arbeit des F\u00f6rsters, die vielen kleinen Waldparzellen zu pflegen, gleicht einer Herkulesaufgabe. Das Mosaik unterschiedlichster Waldstrukturen f\u00fchrt aber dazu, dass viele Waldfunktionen automatisch existieren. Weil es 200 Eigent\u00fcmer gibt, arbeitet Gerig mit \u00bb200 verschiedenen Ausgangslagen, positiv wie negativ\u00ab.<\/p>\n\n\n\n<p>Seine Aufgabe beschreibt er damit, \u00bballes ins grosse Ganze einzuordnen, um dann einen Weg einzuschlagen.\u00ab Der Spielraum ist jedoch begrenzt. Weder k\u00f6nne er etwas am Niederschlag ver\u00e4ndern noch am Boden oder in der Luft. Und wie sich seine Strategien auswirken, zeigt sich erst in f\u00fcnfzig Jahren. Seine Arbeit passiere oft nach dem Motto \u00bbeinfach schauen, ob es funktioniert\u00ab. Dabei st\u00f6sst der Mensch in der Klimakrise Prozesse an, die f\u00fcr die langsam wachsenden B\u00e4ume zu schnell ablaufen k\u00f6nnten: \u00bbIn absehbarer Zeit werden wir vor grossen Herausforderungen stehen\u00ab, sagt Gerig.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Wenn der alte Baum wegkommt, muss der junge schon wachsen<\/h2>\n\n\n\n<p>Seine Arbeit mit dem Licht erfordert ein sensibles Timing: \u00bbWenn der alte Baum wegkommt, muss ein junger schon wachsen. Diese Schnittpunkte m\u00fcssen wir erreichen.\u00ab Hundertfach.<\/p>\n\n\n\n<p>Nur braucht es im Mosaik des Meggerwaldes vor allem eines: Geduld. Und Mut, \u00bbin unserer kurzlebigen Zeit Jahre zu warten, um zu schauen, wie sich etwas entwickelt\u00ab. F\u00f6rster widerstehen dem Druck, schnelle Ergebnisse zu produzieren. Sie denken weniger in Quartalszahlen, als in Jahresringen und wissen: Viele Generationen zuvor schauten in und durch W\u00e4lder. Zusammen mit anderen Lebewesen machen sie W\u00e4lder zu dem, was sie heute sind. Und das l\u00e4sst sich ver\u00e4ndern, langsam.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/riff.media\/cdn-cgi\/image\/width=3840,quality=75\/images\/meggerwald-waldpflege-schweiz-foerster-zukunft-20.jpg?w=3600&amp;s=7c4adf91a8bd3a0a0ff8472a7ed0c99e\" alt=\"F\u00f6rster Lukas Gerig kratzt sich am Hinterkopf und wandert durch seinen Meggerwald in der Zentralschweiz.\"\/><figcaption class=\"wp-element-caption\">F\u00f6rster Lukas Gerig hat keinen leichten Job, muss er doch verschiedenste Interessen im Wald bedienen und balancieren.<\/figcaption><\/figure>\n\n\n\n<p><a href=\"https:\/\/www.riffreporter.de\/de\/ueber-riffreporter\"><\/a><\/p>\n\n\n\n<p>Als F\u00f6rster wei\u00df Gerig auch: Stirbt der Meggerwald, w\u00e4re das ein Problem f\u00fcr die Menschen. Sie sind es, die saubere Luft und gereinigtes Grundwasser brauchen und von der Artenvielfalt, der Naherholung, dem Schutz vor Steinschl\u00e4gen und dem Bauholz zehren. Jeder will etwas anderes vom Wald. Er selbst ist aber nicht auf die Menschheit angewiesen. Der Wald kann Vieles sein, wenn der Mensch inneh\u00e4lt, aufblickt und lernt, zuzuh\u00f6ren.<\/p>","protected":false},"excerpt":{"rendered":"<p>Aus matschigem Boden ragen abges\u00e4gte St\u00fcmpfe, in den Wipfeln zwitschert es: Willkommen im Meggerwald \u2013 einem Chaos mit System, einem Dickicht der Bed\u00fcrfnisse. \u00dcber 200 Eigner\u00efnnen verfolgen hier jeweils eigene Interessen. Aber genau darin k\u00f6nnten sich Chancen verbergen. Eine Reportage aus dem Osten der Schweiz. Der Meggerwald ist kein M\u00e4rchenwald. Er ist Streitort, Experimentierfeld, Lebensraum und Naturexil f\u00fcr St\u00e4dter\u00efnnen. Hier zeigt sich exemplarisch, wie schwierig Waldpflege im 21. Jahrhundert geworden ist \u2013 zwischen Artensterben, Klimakrise, [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1388","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"featured_image_url":[],"post_author":"mark-schoder.de","assigned_categories":"Allgemein","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ein Chaos mit System: Der Meggerwald soll sch\u00fctzen, liefern, heilen -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mark-schoder.de\/en\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ein Chaos mit System: Der Meggerwald soll sch\u00fctzen, liefern, heilen -\" \/>\n<meta property=\"og:description\" content=\"Aus matschigem Boden ragen abges\u00e4gte St\u00fcmpfe, in den Wipfeln zwitschert es: Willkommen im Meggerwald \u2013 einem Chaos mit System, einem Dickicht der Bed\u00fcrfnisse. \u00dcber 200 Eigner\u00efnnen verfolgen hier jeweils eigene Interessen. Aber genau darin k\u00f6nnten sich Chancen verbergen. Eine Reportage aus dem Osten der Schweiz. Der Meggerwald ist kein M\u00e4rchenwald. Er ist Streitort, Experimentierfeld, Lebensraum und Naturexil f\u00fcr St\u00e4dter\u00efnnen. Hier zeigt sich exemplarisch, wie schwierig Waldpflege im 21. Jahrhundert geworden ist \u2013 zwischen Artensterben, Klimakrise, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mark-schoder.de\/en\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-19T17:34:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-19T17:37:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/riff.media\/cdn-cgi\/image\/width=3840,quality=75\/images\/meggerwald-waldpflege-schweiz-foerster-zukunft-11.jpg?w=2300&amp;h=1293&amp;fit=crop-50-35&amp;s=a692e34013f1b996739e640d3dda65b5\" \/>\n<meta name=\"author\" content=\"mark-schoder.de\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"mark-schoder.de\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/mark-schoder.de\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/mark-schoder.de\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/\"},\"author\":{\"name\":\"mark-schoder.de\",\"@id\":\"https:\/\/mark-schoder.de\/#\/schema\/person\/106d22131c49833aef6d346f82ba8f52\"},\"headline\":\"Ein Chaos mit System: Der Meggerwald soll sch\u00fctzen, liefern, heilen\",\"datePublished\":\"2025-08-19T17:34:06+00:00\",\"dateModified\":\"2025-08-19T17:37:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/mark-schoder.de\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/\"},\"wordCount\":2134,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/mark-schoder.de\/#\/schema\/person\/106d22131c49833aef6d346f82ba8f52\"},\"image\":{\"@id\":\"https:\/\/mark-schoder.de\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/riff.media\/cdn-cgi\/image\/width=3840,quality=75\/images\/meggerwald-waldpflege-schweiz-foerster-zukunft-11.jpg?w=2300&amp;h=1293&amp;fit=crop-50-35&amp;s=a692e34013f1b996739e640d3dda65b5\",\"articleSection\":[\"Allgemein\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/mark-schoder.de\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/mark-schoder.de\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/\",\"url\":\"https:\/\/mark-schoder.de\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/\",\"name\":\"Ein Chaos mit System: Der Meggerwald soll sch\u00fctzen, liefern, heilen -\",\"isPartOf\":{\"@id\":\"https:\/\/mark-schoder.de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/mark-schoder.de\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/mark-schoder.de\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/riff.media\/cdn-cgi\/image\/width=3840,quality=75\/images\/meggerwald-waldpflege-schweiz-foerster-zukunft-11.jpg?w=2300&amp;h=1293&amp;fit=crop-50-35&amp;s=a692e34013f1b996739e640d3dda65b5\",\"datePublished\":\"2025-08-19T17:34:06+00:00\",\"dateModified\":\"2025-08-19T17:37:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/mark-schoder.de\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/mark-schoder.de\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/mark-schoder.de\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/#primaryimage\",\"url\":\"https:\/\/riff.media\/cdn-cgi\/image\/width=3840,quality=75\/images\/meggerwald-waldpflege-schweiz-foerster-zukunft-11.jpg?w=2300&amp;h=1293&amp;fit=crop-50-35&amp;s=a692e34013f1b996739e640d3dda65b5\",\"contentUrl\":\"https:\/\/riff.media\/cdn-cgi\/image\/width=3840,quality=75\/images\/meggerwald-waldpflege-schweiz-foerster-zukunft-11.jpg?w=2300&amp;h=1293&amp;fit=crop-50-35&amp;s=a692e34013f1b996739e640d3dda65b5\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/mark-schoder.de\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/mark-schoder.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ein Chaos mit System: Der Meggerwald soll sch\u00fctzen, liefern, heilen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/mark-schoder.de\/#website\",\"url\":\"https:\/\/mark-schoder.de\/\",\"name\":\"Mark Schoder\",\"description\":\"Umwelt- und Lokaljournalist: Radikal hoffnungsvoll in Klima- und Umweltkrise\",\"publisher\":{\"@id\":\"https:\/\/mark-schoder.de\/#\/schema\/person\/106d22131c49833aef6d346f82ba8f52\"},\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\/\/mark-schoder.de\/#\/schema\/person\/106d22131c49833aef6d346f82ba8f52\",\"name\":\"mark-schoder.de\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/mark-schoder.de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/mark-schoder.de\/wp-content\/uploads\/2025\/08\/cropped-logo-1-edited.jpg\",\"contentUrl\":\"https:\/\/mark-schoder.de\/wp-content\/uploads\/2025\/08\/cropped-logo-1-edited.jpg\",\"width\":474,\"height\":474,\"caption\":\"mark-schoder.de\"},\"logo\":{\"@id\":\"https:\/\/mark-schoder.de\/#\/schema\/person\/image\/\"},\"sameAs\":[\"https:\/\/mark-schoder.de\"],\"url\":\"https:\/\/mark-schoder.de\/en\/author\/mark-schoder-de\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ein Chaos mit System: Der Meggerwald soll sch\u00fctzen, liefern, heilen -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mark-schoder.de\/en\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/","og_locale":"en_US","og_type":"article","og_title":"Ein Chaos mit System: Der Meggerwald soll sch\u00fctzen, liefern, heilen -","og_description":"Aus matschigem Boden ragen abges\u00e4gte St\u00fcmpfe, in den Wipfeln zwitschert es: Willkommen im Meggerwald \u2013 einem Chaos mit System, einem Dickicht der Bed\u00fcrfnisse. \u00dcber 200 Eigner\u00efnnen verfolgen hier jeweils eigene Interessen. Aber genau darin k\u00f6nnten sich Chancen verbergen. Eine Reportage aus dem Osten der Schweiz. Der Meggerwald ist kein M\u00e4rchenwald. Er ist Streitort, Experimentierfeld, Lebensraum und Naturexil f\u00fcr St\u00e4dter\u00efnnen. Hier zeigt sich exemplarisch, wie schwierig Waldpflege im 21. Jahrhundert geworden ist \u2013 zwischen Artensterben, Klimakrise, [&hellip;]","og_url":"https:\/\/mark-schoder.de\/en\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/","article_published_time":"2025-08-19T17:34:06+00:00","article_modified_time":"2025-08-19T17:37:13+00:00","og_image":[{"url":"https:\/\/riff.media\/cdn-cgi\/image\/width=3840,quality=75\/images\/meggerwald-waldpflege-schweiz-foerster-zukunft-11.jpg?w=2300&amp;h=1293&amp;fit=crop-50-35&amp;s=a692e34013f1b996739e640d3dda65b5","type":"","width":"","height":""}],"author":"mark-schoder.de","twitter_card":"summary_large_image","twitter_misc":{"Written by":"mark-schoder.de","Est. reading time":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mark-schoder.de\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/#article","isPartOf":{"@id":"https:\/\/mark-schoder.de\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/"},"author":{"name":"mark-schoder.de","@id":"https:\/\/mark-schoder.de\/#\/schema\/person\/106d22131c49833aef6d346f82ba8f52"},"headline":"Ein Chaos mit System: Der Meggerwald soll sch\u00fctzen, liefern, heilen","datePublished":"2025-08-19T17:34:06+00:00","dateModified":"2025-08-19T17:37:13+00:00","mainEntityOfPage":{"@id":"https:\/\/mark-schoder.de\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/"},"wordCount":2134,"commentCount":0,"publisher":{"@id":"https:\/\/mark-schoder.de\/#\/schema\/person\/106d22131c49833aef6d346f82ba8f52"},"image":{"@id":"https:\/\/mark-schoder.de\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/#primaryimage"},"thumbnailUrl":"https:\/\/riff.media\/cdn-cgi\/image\/width=3840,quality=75\/images\/meggerwald-waldpflege-schweiz-foerster-zukunft-11.jpg?w=2300&amp;h=1293&amp;fit=crop-50-35&amp;s=a692e34013f1b996739e640d3dda65b5","articleSection":["Allgemein"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mark-schoder.de\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mark-schoder.de\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/","url":"https:\/\/mark-schoder.de\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/","name":"Ein Chaos mit System: Der Meggerwald soll sch\u00fctzen, liefern, heilen -","isPartOf":{"@id":"https:\/\/mark-schoder.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mark-schoder.de\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/#primaryimage"},"image":{"@id":"https:\/\/mark-schoder.de\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/#primaryimage"},"thumbnailUrl":"https:\/\/riff.media\/cdn-cgi\/image\/width=3840,quality=75\/images\/meggerwald-waldpflege-schweiz-foerster-zukunft-11.jpg?w=2300&amp;h=1293&amp;fit=crop-50-35&amp;s=a692e34013f1b996739e640d3dda65b5","datePublished":"2025-08-19T17:34:06+00:00","dateModified":"2025-08-19T17:37:13+00:00","breadcrumb":{"@id":"https:\/\/mark-schoder.de\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mark-schoder.de\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mark-schoder.de\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/#primaryimage","url":"https:\/\/riff.media\/cdn-cgi\/image\/width=3840,quality=75\/images\/meggerwald-waldpflege-schweiz-foerster-zukunft-11.jpg?w=2300&amp;h=1293&amp;fit=crop-50-35&amp;s=a692e34013f1b996739e640d3dda65b5","contentUrl":"https:\/\/riff.media\/cdn-cgi\/image\/width=3840,quality=75\/images\/meggerwald-waldpflege-schweiz-foerster-zukunft-11.jpg?w=2300&amp;h=1293&amp;fit=crop-50-35&amp;s=a692e34013f1b996739e640d3dda65b5"},{"@type":"BreadcrumbList","@id":"https:\/\/mark-schoder.de\/ein-chaos-mit-system-der-meggerwald-soll-schuetzen-liefern-heilen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/mark-schoder.de\/"},{"@type":"ListItem","position":2,"name":"Ein Chaos mit System: Der Meggerwald soll sch\u00fctzen, liefern, heilen"}]},{"@type":"WebSite","@id":"https:\/\/mark-schoder.de\/#website","url":"https:\/\/mark-schoder.de\/","name":"Mark Schoder","description":"Umwelt- und Lokaljournalist: Radikal hoffnungsvoll in Klima- und Umweltkrise","publisher":{"@id":"https:\/\/mark-schoder.de\/#\/schema\/person\/106d22131c49833aef6d346f82ba8f52"},"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/mark-schoder.de\/#\/schema\/person\/106d22131c49833aef6d346f82ba8f52","name":"mark-schoder.de","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mark-schoder.de\/#\/schema\/person\/image\/","url":"https:\/\/mark-schoder.de\/wp-content\/uploads\/2025\/08\/cropped-logo-1-edited.jpg","contentUrl":"https:\/\/mark-schoder.de\/wp-content\/uploads\/2025\/08\/cropped-logo-1-edited.jpg","width":474,"height":474,"caption":"mark-schoder.de"},"logo":{"@id":"https:\/\/mark-schoder.de\/#\/schema\/person\/image\/"},"sameAs":["https:\/\/mark-schoder.de"],"url":"https:\/\/mark-schoder.de\/en\/author\/mark-schoder-de\/"}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/mark-schoder.de\/en\/wp-json\/wp\/v2\/posts\/1388"}],"collection":[{"href":"https:\/\/mark-schoder.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mark-schoder.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mark-schoder.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mark-schoder.de\/en\/wp-json\/wp\/v2\/comments?post=1388"}],"version-history":[{"count":3,"href":"https:\/\/mark-schoder.de\/en\/wp-json\/wp\/v2\/posts\/1388\/revisions"}],"predecessor-version":[{"id":1392,"href":"https:\/\/mark-schoder.de\/en\/wp-json\/wp\/v2\/posts\/1388\/revisions\/1392"}],"wp:attachment":[{"href":"https:\/\/mark-schoder.de\/en\/wp-json\/wp\/v2\/media?parent=1388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mark-schoder.de\/en\/wp-json\/wp\/v2\/categories?post=1388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mark-schoder.de\/en\/wp-json\/wp\/v2\/tags?post=1388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}